{"id":24211,"date":"2025-03-20T09:00:00","date_gmt":"2025-03-20T08:00:00","guid":{"rendered":"https:\/\/www.coureurdudimanche.com\/blog\/?p=24211"},"modified":"2025-06-27T11:12:00","modified_gmt":"2025-06-27T09:12:00","slug":"course-entreprise-5-courses-a-faire-avec-vos-equipes","status":"publish","type":"post","link":"https:\/\/www.coureurdudimanche.com\/blog\/course-entreprise-5-courses-a-faire-avec-vos-equipes\/","title":{"rendered":"Course entreprise : 5 courses \u00e0 faire avec vos \u00e9quipes"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"536\" src=\"https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Article-Course-entreprise-1024x536.jpg\" alt=\"\" class=\"wp-image-24273\" srcset=\"https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Article-Course-entreprise-1024x536.jpg 1024w, https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Article-Course-entreprise-300x157.jpg 300w, https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Article-Course-entreprise-768x402.jpg 768w, https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Article-Course-entreprise-1536x804.jpg 1536w, https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Article-Course-entreprise-2048x1072.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Participer \u00e0 une course avec son entreprise, c&rsquo;est bien plus qu&rsquo;un d\u00e9fi sportif. C&rsquo;est une exp\u00e9rience collective, un moyen de renforcer la coh\u00e9sion d&rsquo;\u00e9quipe et une opportunit\u00e9 unique de mettre en avant les valeurs de l&rsquo;entreprise : solidarit\u00e9, engagement et performance.<\/p>\n\n\n\n<p>Que vous soyez une entreprise soucieuse de l&rsquo; environnement, engag\u00e9e pour la sant\u00e9, ou simplement \u00e0 la recherche d&rsquo;un \u00e9v\u00e9nement f\u00e9d\u00e9rateur, voici 5 course incontournables auxquelles participer avec vos \u00e9quipes.<\/p>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2>Run for Planet : courir pour la plan\u00e8te<\/h2>\n\n\n\n<p><a href=\"https:\/\/runforplanet.fr\/\" data-type=\"URL\" data-id=\"https:\/\/runforplanet.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Run for Planet<\/a> est la premi\u00e8re course en France \u00e0 \u00eatre \u00e9co-con\u00e7ue et 100% engag\u00e9e pour l&rsquo;environnement. Organis\u00e9e dans plusieurs grandes villes (Paris, Lyon, Bordeaux, Nantes, Toulouse), elle permet aux entreprises de mobiliser leurs \u00e9quipes autour d&rsquo;une cause essentielle : la protection de la plan\u00e8te.<\/p>\n\n\n\n<p>Pourquoi participer avec votre entreprise ?<\/p>\n\n\n\n<ul><li>Un \u00e9v\u00e9nement \u00e9co-responsable qui sensibilise \u00e0 la transition \u00e9cologique,<\/li><li>Un challenge sportif accessible \u00e0 tous (distances de 5 km et 10 km),<\/li><li>Une partie des b\u00e9n\u00e9fices revers\u00e9e \u00e0 des associations environnementales.<\/li><\/ul>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2>Odyss\u00e9a : courir pour la lutte contre le cancer du sein<\/h2>\n\n\n\n<p>Depuis plus de 20 ans, <a href=\"https:\/\/odyssea.info\/\" data-type=\"URL\" data-id=\"https:\/\/odyssea.info\/\" target=\"_blank\" rel=\"noreferrer noopener\">Odyss\u00e9a<\/a> rassemble des milliers de coureurs et marcheurs \u00e0 travers la France pour soutenir la recherche contre le cancer du sein.<\/p>\n\n\n\n<p>Pourquoi inscrire votre entreprise ?<\/p>\n\n\n\n<ul><li>Un \u00e9v\u00e9nement solidaire, avec des fonds revers\u00e9s aux h\u00f4pitaux et associations,<\/li><li>Un challenge inclusif ouvert aux coureurs et marcheurs de tous niveaux,<\/li><li>Une forte dimension humaine, parfaite pour f\u00e9d\u00e9rer et motiver vos collaborateurs.<\/li><\/ul>\n\n\n\n<p>Odyss\u00e9a a lieu dans plusieurs villes fran\u00e7aises comme Paris, Nantes, Bayonne, Dijon, Toulouse, Chamb\u00e9ry\u2026<\/p>\n\n\n\n<p>Une course qui a du sens et qui renforce l&rsquo;engagement de votre entreprise aupr\u00e8s de ses collaborateurs !<\/p>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2>La Course des Lumi\u00e8res : une course nocturne solidaire<\/h2>\n\n\n\n<p>La <a href=\"https:\/\/www.coursedeslumieres.com\/\" data-type=\"URL\" data-id=\"https:\/\/www.coursedeslumieres.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Course des Lumi\u00e8res<\/a> est un \u00e9v\u00e9nement sportif et caritatif, organis\u00e9 dans plusieurs grandes villes fran\u00e7aises, pour soutenir la recherche m\u00e9dicale contre le cancer et les maladies neurologiques.<\/p>\n\n\n\n<p>Pourquoi y participer en \u00e9quipe ?<\/p>\n\n\n\n<ul><li>Un format nocturne unique, qui cr\u00e9e une ambiance magique,<\/li><li>Un engagement fort, avec une partie des inscriptions revers\u00e9es \u00e0 la recherche,<\/li><li>Une exp\u00e9rience collective marquante pour vos \u00e9quipes.<\/li><\/ul>\n\n\n\n<p>Un excellent moyen de sensibilisation, tout en partageant un moment fort avec ses coll\u00e8gues !<\/p>\n\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2>La Corporace : la course inter-entreprises par excellence<\/h2>\n\n\n\n<p>La <a href=\"https:\/\/www.corporace.fr\/\" data-type=\"URL\" data-id=\"https:\/\/www.corporace.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Corporace<\/a> est l&rsquo;\u00e9v\u00e9nement incontournable des entreprises qui souhaitent renforcer la coh\u00e9sion de leurs \u00e9quipes \u00e0 travers un d\u00e9fi sportif.<\/p>\n\n\n\n<p>Pourquoi choisir la Corporace pour votre entreprise ?<\/p>\n\n\n\n<ul><li>Un challenge adapt\u00e9 aux entreprises, avec une organisation sur-mesure,<\/li><li>Une ambiance conviviale et comp\u00e9titive,<\/li><li>Un excellent levier pour d\u00e9velopper le team building et le d\u00e9passement de soi.<\/li><\/ul>\n\n\n\n<p>Un format parfait pour renforcer l&rsquo;esprit d&rsquo;\u00e9quipe et votre marque employeur !<\/p>\n\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2>Ekiden : un marathon en \u00e9quipe pour une coh\u00e9sion maximale<\/h2>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/www.finishers.com\/thematiques\/ekiden\" data-type=\"URL\" data-id=\"https:\/\/www.finishers.com\/thematiques\/ekiden\" target=\"_blank\">L&rsquo;Ekiden<\/a>, c&rsquo;est une course de 42,195 km parcourus en \u00e9quipe de 6 coureurs, o\u00f9 chacun r\u00e9alise une distance comprise entre 5 et 10 km. Un vrai travail d&rsquo;\u00e9quipe, o\u00f9 chaque relais compte !<\/p>\n\n\n\n<p>Pourquoi votre entreprise devrait tenter l&rsquo;aventure Ekiden ?<\/p>\n\n\n\n<ul><li>Un format accessible \u00e0 tous les niveaux,<\/li><li>Une exp\u00e9rience collective forte o\u00f9 l&rsquo;entraide est essentielle,<\/li><li>Une opportunit\u00e9 de renforcer l&rsquo;esprit d&rsquo;\u00e9quipe et la motivation des collaborateurs.<\/li><\/ul>\n\n\n\n<p>Les Ekiden sont organis\u00e9s dans plusieurs grandes villes en France , et sont une excellente alternative aux courses classiques individuels.<\/p>\n\n\n\n<p>Une course parfaite pour tester l&rsquo;esprit d&rsquo;\u00e9quipe de votre entreprise tout en prenant du plaisir !<\/p>\n\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2>Equipez vos \u00e9quipes avec des tenues personnalis\u00e9es 100% made in France et \u00e9co-responsables !<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<p>Chez Coureur du Dimanche, nous accompagnons les <strong>entreprises, clubs et organisateurs d&rsquo;\u00e9v\u00e9nements sportifs<\/strong> en proposant une offre de personnalisation textile BtoB sur mesure. Offrez \u00e0 vos \u00e9quipes des v\u00eatements techniques aux couleurs de votre entit\u00e9 pour renforcer votre marque employeur et f\u00e9d\u00e9rer vos collaborateurs autour de valeurs communes. Une solution cl\u00e9 en main pour tous vos \u00e9v\u00e9nements :<\/p>\n\n\n\n<ul><li>Challenges inter-entreprises &amp; marathons corporate,<\/li><li>Team building &amp; \u00e9v\u00e9nements internes,<\/li><li>Promotion du sport en entreprise &amp; bien-\u00eatre des collaborateurs.<\/li><\/ul>\n\n\n\n<p>Notre gamme de personnalisation se compose de 3 offres :<\/p>\n\n\n\n<ul><li><strong>Gamme Premium<\/strong>&nbsp;<ul><li>Technique textile, fabrication fran\u00e7aise, mati\u00e8res recycl\u00e9es.<\/li><\/ul><\/li><\/ul>\n\n\n\n<ul><li><strong>Gamme Standard<\/strong><ul><li>Technique textile, fabrication fran\u00e7aise, mati\u00e8res recycl\u00e9es, confection simplifi\u00e9e.<\/li><\/ul><\/li><\/ul>\n\n\n\n<ul><li><strong>Accessoires de running personnalis\u00e9s<\/strong><\/li><\/ul>\n\n\n\n<p>Ajoutez votre logo, vos couleurs et votre slogan pour une tenue unique qui incarne l&rsquo;ADN de votre entreprise !<\/p>\n\n\n\n<p>100% fabriqu\u00e9 en France, \u00e0 partir de mati\u00e8res recycl\u00e9es pour une approche plus durable et engag\u00e9e.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Linkedin-BtoB-2-1024x1024.png\" alt=\"\" class=\"wp-image-24247\" srcset=\"https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Linkedin-BtoB-2-1024x1024.png 1024w, https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Linkedin-BtoB-2-300x300.png 300w, https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Linkedin-BtoB-2-150x150.png 150w, https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Linkedin-BtoB-2-768x768.png 768w, https:\/\/www.coureurdudimanche.com\/blog\/wp-content\/uploads\/2025\/03\/Linkedin-BtoB-2.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center\">Pr\u00eat \u00e0 donner vie \u00e0 votre projet ?<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Un projet ? Une id\u00e9e ? Nous serions ravis d\u2019en savoir plus !\u00a0<strong>Contactez-nous<\/strong>\u00a0d\u00e8s maintenant pour \u00e9changer sur vos besoins et obtenir un devis personnalis\u00e9.\u00a0<strong>Nous sommes \u00e0 votre \u00e9coute.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Devis en 24\/48H.\u00a0\ud83d\udc4a<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">Mail : florian.bachelard@coureurdudimanche.com<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons aligncenter\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background no-border-radius\" href=\"https:\/\/www.coureurdudimanche.com\/content\/14-personnalisation-groupe-entreprise-vetement\" style=\"background-color:#0071a1\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9couvrir notre offre BtoB<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:46px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<ul class=\"wp-block-latest-posts wp-block-latest-posts__list\"><li><a href=\"https:\/\/www.coureurdudimanche.com\/blog\/coureur-du-dimanche-equipementier-officiel-de-la-deuxieme-edition-de-run-set-match\/\">Coureur du Dimanche, \u00e9quipementier officiel de la deuxi\u00e8me \u00e9dition de Run Set &#038; Match<\/a><\/li>\n<li><a href=\"https:\/\/www.coureurdudimanche.com\/blog\/coureur-du-dimanche-arrive-chez-run-origins-a-pleurtuit-en-bretagne\/\">Coureur du Dimanche arrive chez Run Origins \u00e0 Pleurtuit en Bretagne !<\/a><\/li>\n<li><a href=\"https:\/\/www.coureurdudimanche.com\/blog\/la-nouvelle-collection-dete-summertime-est-arrivee\/\">La nouvelle collection d&rsquo;\u00e9t\u00e9 SUMMERTIME est arriv\u00e9e.<\/a><\/li>\n<li><a href=\"https:\/\/www.coureurdudimanche.com\/blog\/coureur-du-dimanche-equipementier-officier-du-la-course-run-set-match\/\">Coureur Du Dimanche : Equipementier officiel de la course Run, Set &#038; Match<\/a><\/li>\n<li><a href=\"https:\/\/www.coureurdudimanche.com\/blog\/textile-de-running-en-magasin-faites-la-difference-avec-coureur-du-dimanche\/\">Textile de Running en magasin : faites la diff\u00e9rence avec Coureur Du Dimanche<\/a><\/li>\n<\/ul>\n\n\n<div style=\"height:46px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Que vous soyez une entreprise soucieuse de l&rsquo; environnement, engag\u00e9e pour la sant\u00e9, ou simplement \u00e0 la recherche d&rsquo;un \u00e9v\u00e9nement f\u00e9d\u00e9rateur, voici 5 course incontournables auxquelles participer avec vos \u00e9quipes.<\/p>\n","protected":false},"author":5,"featured_media":24273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[231,300],"tags":[706,688,14,27,687,686,246,529,707,664,663,665,537,695,656,704,613],"_links":{"self":[{"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/posts\/24211"}],"collection":[{"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/comments?post=24211"}],"version-history":[{"count":71,"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/posts\/24211\/revisions"}],"predecessor-version":[{"id":24284,"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/posts\/24211\/revisions\/24284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/media\/24273"}],"wp:attachment":[{"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/media?parent=24211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/categories?post=24211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coureurdudimanche.com\/blog\/wp-json\/wp\/v2\/tags?post=24211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}